{"id":12880,"date":"2023-08-09T09:21:08","date_gmt":"2023-08-09T09:21:08","guid":{"rendered":"https:\/\/surfintriptravel.com\/aviso-legal\/"},"modified":"2023-08-16T12:35:45","modified_gmt":"2023-08-16T12:35:45","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/surfintriptravel.com\/it\/aviso-legal\/","title":{"rendered":"Note legale"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"12880\" class=\"elementor elementor-12880 elementor-10815\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-88f8ac5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"88f8ac5\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a15a5ab\" data-id=\"a15a5ab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fa9bf09 elementor-align-left elementor-widget elementor-widget-breadcrumbs\" data-id=\"fa9bf09\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/surfintriptravel.com\/wp-content\/plugins\/elementor-pro\/assets\/css\/widget-theme-elements.min.css\"><p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/surfintriptravel.com\/it\/\">Home<\/a><\/span><\/span><\/p>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5724f96 elementor-widget elementor-widget-heading\" data-id=\"5724f96\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Termini e condizioni generali<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ab596e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ab596e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c733757\" data-id=\"c733757\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1980080 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"1980080\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 08-11-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p><strong>1. Premessa<\/strong><\/p><p>\u00a0<\/p><p>I presenti Termini e Condizioni generali (d\u2019ora in poi globalmente i \u201cTermini\u201d) forniscono informazioni importanti riguardanti il funzionamento dei nostri servizi, i vostri diritti legali, mezzi di ricorso, requisiti, limitazioni e restrizioni, una clausola relativa alla giurisdizione e al foro delle controversie, e gli obblighi di rispettare le leggi e i regolamenti applicabili. I servizi comprendono tutti i servizi della Surf Academy (d\u2019ora in poi globalmente i servizi della \u201cSurf Academy\u201d), del Surf Camp di Fuerteventura (d\u2019ora in poi globalmente i servizi del \u201cSurf Camp\u201d) e l\u2019offerta di pacchetti surf camps in altre localit\u00e0 in collaborazione con i partners (d\u2019ora in poi globalmente i servizi del \u201cPartners Surf Camp\u201d) .<\/p><p>\u00a0<\/p><p>Surfintrip fornisce una piattaforma online di booking che consente di prenotare in maniera semplice e veloce tutti i servizi (d\u2019ora in poi globalmente il \u201cServizio\u201d o i \u201cServizi\u201d). Il Servizio \u00e8 accessibile su www.surfintrip.com (d\u2019ora in poi globalmente il \u201cSito\u201d) e mediante qualsiasi altro sito Web attraverso cui Surfintrip renda disponibili detti Servizi. Utilizzando il Sito, Lei accetta di conformarsi e di essere legalmente vincolato dai termini e dalle condizioni dei presenti Termini, a prescindere dal fatto che divenga o meno un utente registrato dei Servizio. I presenti Termini costituiscono un accordo vincolante tra Lei e Surfintrip. Se Lei non \u00e8 d&#8217;accordo con i presenti Termini, non avr\u00e0 alcun diritto di ottenere informazioni o di altrimenti continuare ad utilizzare il Sito o il Servizio. La mancata osservanza di questi Termini nell\u2019utilizzo del Sito pu\u00f2 comportare sanzioni civili e penali per Lei.<\/p><p>\u00a0<\/p><p>Se Lei sta usando il Sito o il Servizio, la parte con cui sta concludendo il relativo contratto \u00e8 Surfintrip SCP con sede legale in Calle Cangrejo n. 16, Corralejo, 35660 Oliva (LA) \u2013 Palmas (LA), NIF (VAT) n. J76214683.<\/p><p>\u00a0<\/p><p>Determinate aree del Sito, nonch\u00e9 l&#8217;accesso o l&#8217;uso da parte Sua di determinati aspetti del Servizio, potrebbero avere termini e condizioni diversi o potrebbero richiederLe di acconsentire e accettare termini e condizioni aggiuntivi. Qualora vi sia un conflitto tra i presenti Termini e i termini e le condizioni pubblicati per una specifica area del Sito e del Servizio, questi ultimi avranno la precedenza per quanto riguarda l&#8217;uso o l&#8217;accesso a quell&#8217;area del Sito e del Servizio da parte Sua.<\/p><p>\u00a0<\/p><p>Lei riconosce e accetta che, accedendo o utilizzando il sito o i Servizi, Lei indica di aver letto e di comprendere e accettare di essere vincolato dai presenti termini, a prescindere dal fatto che sia registrato o meno sul sito. Se lei non acconsente ai presenti termini, non ha alcun diritto di accedere o di utilizzare il sito, il Servizio o i contenuti.\u00a0<\/p><p>\u00a0<\/p><p>Se Lei accetta o acconsente di osservare i presenti Termini per conto di una societ\u00e0 o di altra entit\u00e0 legale, dichiara e garantisce di avere l&#8217;autorit\u00e0 di vincolare tale societ\u00e0 o altra entit\u00e0 legale ai presenti Termini e, in tale eventualit\u00e0, \u201cLei\u201d e \u201cSuo\u201d si riferiranno e applicheranno a detta societ\u00e0 o altra entit\u00e0 legale.<\/p><p>\u00a0<\/p><p>Surfintrip si riserva il diritto, a sua sola discrezione, di modificare il Sito o i Servizi ovvero di modificare questi Termini, incluse le tariffe dei Servizi in qualsiasi momento e senza previa notifica. Nel caso in cui dovessimo modificare i presenti Termini, pubblicheremo tali modifiche sul Sito oppure Le forniremo notifica della variazione. Aggiorneremo anche la \u201cData ultimo aggiornamento\u201d all&#8217;inizio dei presenti Termini. Continuando ad accedere o ad utilizzare il Sito o i Servizi dalla pubblicazione di una modifica del Sito oppure dall&#8217;invio della notifica di una variazione, Lei indica di accettare di essere vincolato da tali Termini modificati. Qualora ritenesse non accettabili tali modifiche, la Sua unica possibilit\u00e0 di ricorso sar\u00e0 quella di cessare l\u2019utilizzo del Sito e dei Servizi in questione.<\/p><p>\u00a0<\/p><p>La mancata applicazione da parte di Surfintrip di qualunque diritto o disposizione di questi Termini non costituir\u00e0 rinuncia all\u2019esercizio futuro di tale diritto o disposizione. La rinuncia a tale diritto o disposizione sar\u00e0 effettiva unicamente se elaborata per iscritto e firmata da un rappresentante opportunamente autorizzato di Surfintrip.<\/p><p>\u00a0<\/p><p><strong>2. I Servizi \u201cSurf Academy\u201d e \u201cSurf Camp\u201d di Fuerteventura<\/strong><\/p><p>\u00a0<\/p><p>I servizi della \u201cSurf Academy\u201d e del \u201cSurf Camp\u201d prevedono l\u2019organizzazione e l\u2019erogazione di corsi di surf professionali e di pacchetti surf camps (che includono alloggio, corso e altre attivit\u00e0 strettamente collegate al surf) per qualsiasi livello, realizzati a Fuerteventura.<\/p><p>\u00a0<\/p><p><strong>2.1 Requisiti di base<\/strong><\/p><p>\u00a0<\/p><p>Per accedere ai Servizi della \u201cSurf Academy\u201d e del \u201cSurf Camp\u201d di Fuerteventura, Lei dichiara di essere fisicamente in forma e in grado di nuotare. Lei, inoltre, conferma e dichiara, da un punto di vista medico, che non c&#8217;\u00e8 niente che impedisca Lei di esercitare lo sport del surf.<\/p><p>\u00a0<\/p><p><strong>2.2 Materiale tecnico<\/strong><\/p><p>\u00a0<\/p><p>Lei deve fare un uso ragionevole del materiale tecnico di Surfintrip concesso in uso temporaneo e accettare la responsabilit\u00e0 per la sostituzione di tutto il materiale perso o danneggiato per negligenza o mal uso da parte Sua. Qualsiasi materiale che viene sostituito deve essere pagato al valore di mercato e valutato da Surfintrip. Nella fattispecie di materiale danneggiato, lo stesso diventa di Sua propriet\u00e0.<\/p><p>\u00a0<\/p><p><strong>2.3 Comportamento Irresponsabile<\/strong><\/p><p>\u00a0<\/p><p>In caso di utilizzo dei nostri Servizi, Lei \u00e8 tenuto a seguire gli ordini e le istruzioni degli Istruttori di Surfintrip. In caso di comportamento irresponsabile quali rischi per l&#8217;integrit\u00e0 fisica o l&#8217;immagine di altri clienti o di Surfintrip, Lei pu\u00f2 essere escluso dai Servizi acquistati senza preavviso e senza aver diritto alla restituzione dell\u2019intero importo sostenuto per gli stessi.<\/p><p>\u00a0<\/p><p><strong>2.4 In caso di minori<\/strong><\/p><p>\u00a0<\/p><p>In caso di acquisto dei Servizi da parte di un minore di 18 anni, \u00e8 necessaria un autorizzazione scritta e firmata da parte di un genitore e\/o tutore che dovr\u00e0 essere inoltrata via email all\u2019indirizzo info@surfintrip.com almeno 7 giorni prima della data di inizio del Servizio. Surfintrip si riserva il diritto, a sua esclusiva discrezione, di erogare i propri Servizi ai minori di 18 anni in assenza della documentazione richiesta.<\/p><p>\u00a0<\/p><p><strong>3. Il Servizio \u201cPartners Surf Camp\u201d<\/strong><\/p><p>\u00a0<\/p><p>Il servizio \u201cPartners Surf Camp\u201d \u00e8 il servizio attraverso il quale Surfintrip, in seguito ad una selezione di partners qualificati che rispettano determinati standard qualitativi, offre pacchetti surf camps di terze parti (che includono almeno alloggio, lezioni di surf di qualsiasi livello e altre attivit\u00e0 correlate) in altre destinazioni surfistiche presenti al d\u00ec fuori di Fuerteventura.<\/p><p>\u00a0<\/p><p>Surfintrip non \u00e8 titolare n\u00e9 gestore di propriet\u00e0, incluse, a puro titolo esemplificativo, stanze di hotel, stanze di motel, altre sistemazioni o Alloggi, n\u00e9 \u00e8 fornitore di propriet\u00e0, incluse, a puro titolo esemplificativo, stanze di hotel, stanze di motel, altre sistemazioni o Alloggi e Surfintrip non possiede, vende, rivende, fornisce, provvede, affitta, subaffitta, gestisce e\/o controlla propriet\u00e0, incluse, a puro titolo esemplificativo, stanze di hotel, stanze di motel, altre sistemazioni o Alloggi, servizi di trasporto o di viaggio. Se non espressamente indicato diversamente sul Sito Surfintrip, le responsabilit\u00e0 di Surfintrip sono limitate a: (a) rendere disponibili il Sito e i Servizi.<\/p><p>\u00a0<\/p><p>Surfintrip non controlla e non pu\u00f2 controllare la condizione, la legalit\u00e0 o l&#8217;idoneit\u00e0 di alcun alloggio. Surfintrip non \u00e8 responsabile ed esclude qualsiasi responsabilit\u00e0 in relazione agli alloggi dei Partners. Di conseguenza, qualsiasi prenotazione verr\u00e0 effettuata ad esclusivo rischio dell&#8217;ospite. Inoltre, Surfintrip pu\u00f2, a sua esclusiva discrezione, promuovere alcuni pacchetti.<\/p><p>\u00a0<\/p><p>La sezione pu\u00f2 includere, a titolo esemplificativo, un programma di giornate tipo proposto da un eventuale organizzatore di parte terza, indicazioni sui surf spot, trasporto da e per l\u2019aeroporto gestito ed erogato dal proprietario dell\u2019alloggio e\/o da un suo fornitore, i consigli sulla best surf season, su dove mangiare, sui luoghi da visitare, sui servizi inclusi e non.<\/p><p>\u00a0<\/p><p><strong>3.1 Commissioni di servizio e parity rate<\/strong><\/p><p>\u00a0<\/p><p>Per il servizio \u201cPartners surf camp\u201d, come corrispettivo per l&#8217;uso del Sito e dei relativi servizi, Surfintrip addebita il pagamento delle Commissioni di Servizio esclusivamente al proprietario. Resta inteso che Surfintrip addebita le Commissioni di Servizio al proprietario solo in caso di prenotazione confermata.<\/p><p>\u00a0<\/p><p>Laddove applicabili, potrebbero essere addebitate anche le Imposte (come l&#8217;IVA in Europa) in relazione alle Commissioni del Proprietario.\u00a0<\/p><p>\u00a0<\/p><p>Surfintrip deduce le Commissioni del Proprietario dal Prezzo del pacchetto prima di versare il compenso al Proprietario come descritto in questi Termini. Le commissioni del proprietario sono, come precedentemente indicato, incluse nel Prezzo Totale.\u00a0<\/p><p>\u00a0<\/p><p>Non sono previste commissioni a carico dell&#8217;Ospite.<\/p><p>\u00a0<\/p><p>Il proprietario, al fine di fornire un prezzo congruo, dovr\u00e0 tenere in considerazione che il prezzo finale include le commissioni di servizio di Surfintrip.<\/p><p>\u00a0<\/p><p>Resta inteso che il Proprietario pu\u00f2 offrire i propri pacchetti surf camps attraverso siti internet o altro, sempre ed in ogni caso, tuttavia, a prezzi non inferiori (il cosiddetto \u201cParity rate\u201d) a quelli trasmessi a Surfintrip. In caso di inadempimento del proprietario alle pattuizioni contenute nel presente punto, Surfintrip potr\u00e0 trattenere per ciascuna prenotazione di pacchetto surf camp venduta attraverso il suo portale, oltre alla percentuale a titolo di corrispettivo una ulteriore percentuale pari al 5%, a titolo di penale.<\/p><p>\u00a0<\/p><p>Resta inteso che Surfintrip tratterr\u00e0 sul prezzo finale di vendita una percentuale (come di seguito specificata) a titolo di compenso per l\u2019uso della piattaforma e dei relativi servizi, per le attivit\u00e0 svolte di promozione, di posizionamento e di user experience attraverso il portale Surfintrip.com.\u00a0<\/p><p>\u00a0<\/p><p>Le commissioni addebitate da Surfintrip al proprietario in caso di vendita attraverso il portale surfintrip.com sono le seguenti:<\/p><ul><li>Commissioni di servizio per tutti i\u00a0<strong>Partners surfcamp<\/strong>\u00a0escluso le barche:\u00a0<strong>15%<\/strong>\u00a0(escluso VAT ove applicabile);<\/li><li>Commissioni di servizio per le\u00a0<strong>barche<\/strong>:\u00a0<strong>20%<\/strong>\u00a0(escluso VAT ove applicabile).\u00a0<\/li><\/ul><p>\u00a0<\/p><p>I saldi verranno versati da Surfintrip al Proprietario per mezzo di PayPal o deposito diretto o altro metodo di pagamento descritto sul Sito, nella valuta Euro. Gli importi potranno essere arrotondati per difetto o per eccesso secondo quanto descritto nei presenti Termini.<\/p><p>\u00a0<\/p><p>Si prega di notare che Surfintrip potr\u00e0 applicare o dedurre i costi di elaborazione della valuta straniera su o da qualsiasi pagamento effettuato o ricevuto da parte di Surfintrip in valute diverse dall\u2019Euro. Salvo quanto diversamente disposto nel presente documento, le Commissioni di Servizio non sono rimborsabili.<\/p><p>\u00a0<\/p><p><strong>3.2 Condotta dell\u2019utente<\/strong><\/p><p>\u00a0<\/p><p>L\u2019Utente comprende e accetta di essere il solo responsabile dell\u2019osservanza di qualsiasi legge, norma, regolamento e obbligo fiscale che possa essere applicabile all\u2019uso del Sito, del Servizio e dei Contenuti. In relazione all&#8217;utilizzo del Sito, del Servizio e dei Contenuti da parte Sua, l\u2019Utente s&#8217;impegna ad utilizzare il Sito, il Servizio o i Contenuti esclusivamente per le finalit\u00e0 che sono espressamente autorizzati da questi Termini.<\/p><p>\u00a0<\/p><p>Surfintrip ha il diritto di svolgere indagini e di promuovere un procedimento legale in caso di violazione di qualsivoglia clausola di questi Termini nella misura massima consentita dalla legge.<\/p><p>\u00a0<\/p><p>Surfintrip pu\u00f2 accedere, conservare e comunicare le Sue informazioni se \u00e8 tenuta a farlo per legge, o se crede in buona fede che ci\u00f2 sia ragionevolmente necessario per rispondere a reclami rivolti contro Surfintrip o adempiere ordini di natura processuale, attuare e gestire i nostri accordi con gli utenti. Lei riconosce che Surfintrip non ha alcun obbligo di monitorare l&#8217;accesso o l&#8217;utilizzo del Sito, del Servizio o dei Contenuti da parte Sua, o di analizzare o modificare qualsivoglia Contenuto degli Utenti, ma ha il diritto di far ci\u00f2 allo scopo di gestire e migliorare il Sito e i Servizi (comprese, ad esempio, le finalit\u00e0 di prevenzione delle frodi, valutazioni dei rischi, assistenza alla clientela), per garantire l&#8217;osservanza dei presenti Termini da parte Sua, per conformarsi con la legge applicabile o con una risoluzione di un tribunale, di un&#8217;agenzia amministrativa o di un altro ente governativo, per rispondere a contenuti che ritiene in altro modo reprensibili o secondo quanto previsto nei presenti Termini. Surfintrip si riserva il diritto, in qualsiasi momento e senza previa notifica, di rimuovere o disabilitare l&#8217;accesso ai Contenuti che Surfintrip, a sua sola discrezione, consideri discutibili per qualsivoglia ragione, in violazione dei presenti Termini, o altrimenti dannosi per il Sito o i Servizi.\u00a0<\/p><p>\u00a0<\/p><p>Se Lei risiede presso qualcuno che ritiene stia agendo o che abbia agito in maniera inappropriata, oppure ospita qualcuno che ritiene stia agendo o abbia agito in maniera inappropriata, incluso, a puro titolo esemplificativo, qualcuno che (i) mette in atto comportamenti offensivi, violenti o sessualmente inappropriati, (ii) sospetta abbia rubato, o (iii) mette in atto qualsiasi altro comportamento molesto, Lei dovr\u00e0 immediatamente segnalare tale persona alle autorit\u00e0 competenti e quindi a Surfintrip, inviandoci il numero della Sua stazione di polizia e del Suo verbale all\u2019indirizzo info@surfintrip.com; a condizione che la denuncia non ci obblighi ad intraprendere azioni al di l\u00e0 di quanto richiesto dalla legge (qualora vi sia), o ci induca ad incorrere in qualsivoglia responsabilit\u00e0 verso di Lei.<\/p><p>\u00a0<\/p><p><strong>3.3 Gestione dei danni agli alloggi<\/strong><\/p><p>\u00a0<\/p><p>L\u2019Ospite \u00e8 responsabile di lasciare l&#8217;Alloggio nelle condizioni in cui si trovava al suo arrivo. L\u2019Ospite riconosce e accetta che \u00e8 responsabile dei propri atti od omissioni, nonch\u00e9 degli atti od omissioni di qualsiasi singolo individuo che inviti, o a cui venga altrimenti consentito l&#8217;accesso nell&#8217;Alloggio. Nell&#8217;eventualit\u00e0 in cui un Proprietario lamenti e fornisca la prova di danni, inclusi, a puro titolo esemplificativo, danni alle fotografie, l\u2019Ospite accetta di ripagare il costo della sostituzione degli articoli danneggiati con articoli di pari valore. Una volta notificato il reclamo e ottenute settantadue (72) ore per rispondere, il pagamento verr\u00e0 addebitato e prelevato dalla carta di credito archiviata nell\u2019account Surfintrip dell\u2019Ospite. Surfintrip si riserva il diritto di addebitare somme sulla carta di credito archiviata nel Account Surfintrip, o di altrimenti incassare il pagamento direttamente presso l\u2019Ospite, e di perseguire con qualsiasi mezzo disponibile a Surfintrip a tal proposito. Qualora non riuscissimo ad addebitare la carta di credito in archivio o a riscuotere altrimenti il pagamento, l\u2019Ospite accetta di versare il pagamento di qualsiasi danno arrecato all&#8217;Alloggio al Proprietario.<\/p><p>\u00a0<\/p><p>Sia gli Ospiti che i Proprietari accettano di collaborare e di assistere Surfintrip in buona fede, nonch\u00e9 di fornire ad Surfintrip tutte le informazioni e intraprendere tutte le azioni ragionevolmente richieste da Surfintrip, in relazione a qualsiasi reclamo o richiesta di risarcimento effettuati dagli Utenti relativamente agli Alloggi o a qualsivoglia propriet\u00e0 personale o di altro genere situati presso un Alloggio o per quanto riguarda qualunque indagine intrapresa da Surfintrip o da un rappresentante di Surfintrip riguardante l&#8217;uso o l&#8217;abuso del Sito o dei Servizi.\u00a0<\/p><p>\u00a0<\/p><p>L\u2019Ospite riconosce e accetta che Surfintrip si riserva il diritto, a propria esclusiva discrezione, di presentare qualsivoglia richiesta di risarcimento che ricada sotto la polizza assicurativa del Proprietario, del Locatore ovvero altra polizza assicurativa correlata a qualsiasi danno o perdita che Lei possa aver causato o di cui si sia reso responsabile, a un Alloggio o a qualunque altra propriet\u00e0 personale o di altro genere situata presso l&#8217;Alloggio.\u00a0<\/p><p>\u00a0<\/p><p><strong>4. Modalit\u00e0 di prenotazione<\/strong><\/p><p>\u00a0<\/p><p>La prenotazione dei Servizi dovra\u0300 essere effettuata via e-mail (booking@surfintrip.com) o attraverso il nostro sito web (www.surfintrip.com) o per telefono (+34 667015604) o via Whatsapp (+34 667015604). Nella prenotazione via e-mail o via telefono dovranno essere indicati: nome, cognome, check-in e check-out, tipologia di servizio prenotato, e-mail e n. di cellulare.<\/p><p>\u00a0<\/p><p>Attraverso il sito, per prenotare un Servizio \u00e8 necessario scegliere il servizio che Lei ha intenzione di acquistare. Una volta scelto il Servizio, le verr\u00e0 richiesto di compilare un form con le informazioni necessarie e di finalizzare il pagamento fornendo i dati richiesti.<\/p><p>\u00a0<\/p><p>La prenotazione \u00e8 valida nel momento in cui, in base alla disponibilita\u0300, Lei ricever\u00e0 una comunicazione via email da parte di Surfintrip con la conferma della prenotazione e dell\u2019avvenuta ricezione del deposito richiesto.<\/p><p>\u00a0<\/p><p><strong>5. Modalit\u00e0 di pagamento<\/strong>\u00a0<\/p><p>\u00a0<\/p><p>La prenotazione del Servizio attraverso il presente sito web prevede il pagamento del 20% dell\u2019intero importo a Surfintrip al momento della prenotazione valido come acconto del totale del servizio acquistato.<\/p><p>\u00a0<\/p><p>La prenotazione del Servizio attraverso e-mail, telefono o whatsapp prevede il pagamento del 20% dell\u2019intero importo a Surfintrip al momento della prenotazione valido come acconto del totale del servizio acquistato.<\/p><p>\u00a0<\/p><p>Il saldo, ovvero il restante 80% dell\u2019intero importo, dovr\u00e0 essere versato in loco al momento del check-in, ovvero il primo giorno del Servizio.\u00a0<\/p><p>\u00a0<\/p><p>Le modalit\u00e0 di pagamento sono bonifico bancario, carta di credito (esclusivamente attraverso il presente sito web), conto Paypal (le commissioni PayPal saranno aggiunte al totale dell&#8217;importo oggetto di pagamento) e contanti. Quest\u2019ultima modalit\u00e0 di pagamento \u00e8 valida solo in loco.<\/p><p>\u00a0<\/p><p><strong>6. Politica di cancellazione<\/strong><\/p><p>\u00a0<\/p><p>La cancellazione della prenotazione e\u0300 possibile in qualsiasi momento e dovra\u0300 essere comunicata in forma scritta via e-mail (booking@surfintrip.com) e\/o attraverso il sito web ed avra\u0300 validita\u0300 il giorno in cui Surfintrip la riceve. La nostra policy in caso di cancellazione e\u0300 la seguente:<\/p><ul><li>In caso di\u00a0restrizioni\u00a0direttamente causate dal Covid-19 (cancellazioni voli, chiusura confini,\u00a0lockdown ecc.), l&#8217;ospite\u00a0riceve un rimborso\u00a0pari al totale (100%)\u00a0del deposito;<\/li><li>Per le cancellazioni effettuate entro 60 giorni prima della data di inizio del Servizio, l\u2019ospite riceve un rimborso pari al totale del deposito;<\/li><li>Per le cancellazioni effettuate tra il 59\u00b0 giorno e il 45\u00b0 girono, prima della data di inizio del Servizio, l\u2019ospite riceve un rimborso pari al 50% dell\u2019importo totale del deposito;<\/li><li>Per le cancellazioni effettuate tra il 44\u00b0 giorno al giorno stesso della data di inizio del Servizio, l\u2019ospite non riceve nessun rimborso del deposito.<\/li><\/ul><p>\u00a0<\/p><p><strong>7. Privacy e Cookies<\/strong><\/p><p>\u00a0<\/p><p>Per tutte le informazioni relative alla politica sulla privacy e sui cookies, si prega di fare riferimento alle rispettive sezioni dedicate nel nostro sito. Il sito Web e i servizi possono contenere collegamenti a siti Web o risorse di terze parti. L&#8217;utente riconosce e accetta che Surfintrip non \u00e8 responsabile per: (a) la disponibilit\u00e0 o l&#8217;accuratezza di tali siti Web o risorse; o (b) il contenuto, i prodotti oi servizi su o disponibili da tali siti Web o risorse. I collegamenti a tali siti Web o risorse non implicano alcun supporto da parte di Surfintrip a tali siti Web o risorse o al contenuto, ai prodotti o ai servizi disponibili da tali siti Web o risorse. L&#8217;utente accetta la responsabilit\u00e0 esclusiva e l&#8217;utente si assume tutti i rischi derivanti dall&#8217;utilizzo di tali siti Web o risorse o del contenuto, dei prodotti o dei servizi su o disponibili da tali siti Web o risorse.<\/p><p>\u00a0<\/p><p>Alcune parti della piattaforma Surfintrip implementano i servizi di mappatura di Google Maps\/Earth, incluse le API (Application Programming Interface) di Google Maps. L&#8217;utilizzo di Google Maps\/Earth \u00e8 soggetto ai termini di utilizzo di Google.<\/p><p>\u00a0<\/p><p><strong>8. Titolarit\u00e0 e copyright<\/strong><\/p><p>\u00a0<\/p><p>I Tutti i marchi, i marchi di servizio, i loghi, i nomi commerciali e qualsiasi altra designazione proprietaria di Surfintrip utilizzata nel presente sono nomi commerciali o nomi commerciali registrati di Surfintrip. Tutti gli altri marchi, i marchi di servizio, i loghi, i nomi commerciali e qualsiasi altra designazione proprietaria sono nomi commerciali o nomi commerciali registrati delle proprie rispettive parti.<\/p><p>\u00a0<\/p><p>Il Sito, i Servizi e i Contenuti sono protetti da diritti d&#8217;autore, marchi e altre leggi, della Spagna, della comunit\u00e0 europea e internazionale. Lei riconosce e accetta che il Sito, i Servizi e i Contenuti, inclusi tutti i relativi diritti di propriet\u00e0 intellettuale, sono di propriet\u00e0 esclusiva di Surfintrip e dei propri licenzianti. Lei non rimuover\u00e0, alterer\u00e0 n\u00e9 oscurer\u00e0 le informazioni relative a diritti d&#8217;autore, marchi, marchi di servizio o altre informazioni di diritti proprietari incorporate o presenti nel Sito, nei Servizi o nei Contenuti.<\/p><p>\u00a0<\/p><p><strong>9. Responsabilit\u00e0 e manleva<\/strong><\/p><p>\u00a0<\/p><p>Surfintrip \u00e8 responsabile della corretta progettazione ed erogazione dei Servizi che offriamo nei termini descritti sul nostro sito web.\u00a0<\/p><p>\u00a0<\/p><p>Lei riconosce e accetta che, nella misura massima consentita dalla legge, l\u2019intero rischio derivante dall\u2019accesso e dall\u2019uso del sito, dei Servizi e dei relativi contenuti e qualsiasi contatto che lei abbia con altri utenti di Surfintrip, sia di persona sia online, sono a suo carico. N\u00e9 Surfintrip n\u00e9 qualunque altra parte coinvolta nella creazione, produzione o pubblicazione del sito, dei Servizi e dei contenuti sar\u00e0 responsabile di qualunque danno accidentale, speciale, esemplare o consequenziale, interruzione di Servizio, danni informatici o malfunzionamento di sistema, n\u00e9 di qualunque danno connesso a lesioni personali o fisiche o disagio emotivo dovuto o connesso a questi termini derivante dall&#8217;uso o dall&#8217;impossibilit\u00e0 di utilizzare il sito, i Servizi o i contenuti, da qualsivoglia comunicazione, interazione o incontro con altri utenti del sito, o dei Servizi, o con altre persone con cui lei comunichi o interagisca come risultato del proprio utilizzo del sito, dei Servizi, indipendentemente dal fatto che tale danno si fondi su una garanzia, un contratto, un illecito (inclusa la negligenza), responsabilit\u00e0 del prodotto o qualunque altra fonte di responsabilit\u00e0 e sia che Surfintrip sia stata informata o meno della possibilit\u00e0 di tale danno, anche qualora un rimedio limitato ai sensi del presente documento non raggiunga il proprio scopo essenziale.<\/p><p>\u00a0<\/p><p>Per tutti i servizi della Surf Academy, la responsabilit\u00e0 di Surfintrip \u00e8 limitata a un massimo di 3 volte l&#8217;importo del costo del Servizio, sempre e fino a quando il danno non \u00e8 stato prodotto a proposito. Surfintrip non \u00e8 responsabile delle circostanze causate dalle condizioni climatiche e nessun rimborso sar\u00e0 erogato a causa delle stesse. Se Lei sceglie di utilizzare il sito, i Servizi o i contenuti, lo fa a suo rischio esclusivo. Nessun consiglio o dato, sia orale che scritto, ottenuto da Surfintrip o attraverso il sito, i Servizi o i contenuti, creer\u00e0 qualsivoglia garanzia non espressamente rilasciata nel presente. Lei s\u2019impegna a liberare, difendere, manlevare e tenere Surfintrip e le sue affiliate e consociate, e i loro funzionari, direttori, dipendenti e agenti indenni da e contro qualsiasi pretesa, responsabilit\u00e0, danni, perdite e spese, inclusi, senza limitazione, ragionevoli onorari legali e contabili, derivanti da, o in qualsiasi modo correlati a (a) l&#8217;accesso o l&#8217;utilizzo del Sito, dei Servizi o dei Contenuti da parte Sua o la violazione dei presenti Termini da parte Sua; (b) il Suo Contenuto degli Utenti; (c) l&#8217;interazione con qualunque Utente, (d) qualsiasi delle seguenti azioni svolte da Lei (e) la prenotazione o l\u2019uso di un Servizio, inclusi, senza limitazione alcuna, qualsiasi lesione, perdita o danno (per risarcimento danni, diretto, accidentale, consequenziale o altrimenti) di qualsivoglia genere che sorga in collegamento con, o come risultato dell\u2019utilizzo del sito o dei Servizi e contenuti.<\/p><p>\u00a0<\/p><p>Surfintrip non riconosce alcuna garanzia che il sito e i servizi, i contenuti inclusi, a puro titolo esemplificativo, soddisfino i suoi requisiti o siano disponibili in modo continuativo, sicuro e privo di errori. Surfintrip non fornisce alcuna garanzia riguardante la qualit\u00e0 di qualsivoglia alloggio, i servizi o i contenuti o l&#8217;accuratezza, tempestivit\u00e0, veridicit\u00e0, completezza o affidabilit\u00e0 di qualsiasi contenuto collettivo ottenuto attraverso il sito e i servizi.<\/p><p>\u00a0<\/p><p>Nessun consiglio o dato, sia orale che scritto, ottenuto da Surfintrip o attraverso il sito, i servizi o i contenuti, creer\u00e0 qualsivoglia garanzia non espressamente rilasciata nel presente.<\/p><p>\u00a0<\/p><p>Lei \u00e8 il solo responsabile di tutte le proprie comunicazioni e interazioni con altri utenti del sito o dei servizi e con altre persone con cui comunica o interagisce in conseguenza del proprio utilizzo del sito o dei servizi, inclusi, a titolo esemplificativo. Surfintrip non rilascia alcuna dichiarazione o garanzia per quanto riguarda la condotta degli utenti del sito o dei servizi o la loro compatibilit\u00e0 con qualsiasi attuale o futuro utente del sito o dei servizi. Lei s&#8217;impegna ad adottare ragionevoli precauzioni in tutte le comunicazioni e interazioni con altri utenti del sito o dei servizi e con altre persone con cui comunica o interagisce in conseguenza del proprio utilizzo del sito o dei servizi, inclusi, fra gli altri, proprietari dei surf camps e ospiti, in particolare se decide di incontrarli offline o di persona, indipendentemente dal fatto che tali incontri siano organizzati da Surfintrip. Indipendentemente dalla nomina di Surfintrip, in qualit\u00e0 di agente provvisorio per la raccolta dei pagamenti dei proprietari dei surf camps allo scopo di ricevere pagamenti dagli ospiti a nome e per conto dei padroni stessi, Surfintrip rinuncia esplicitamente a qualsivoglia responsabilit\u00e0 per azioni o omissioni del proprietario del surf camps nei confronti degli ospiti o di terzi.\u00a0<\/p><p>\u00a0<\/p><p><strong>10. Gestione dei reclami<\/strong><\/p><p>\u00a0<\/p><p>Surfintrip mette a disposizione dei suoi clienti i moduli di reclamo, conformi al modello approvato dal Ministero responsabile per il turismo, nella sua sede operativa sita in Calle Chorlitejo 8, vistas del mar 8, villa n.2, Corralejo (La Oliva), dal luned\u00ec al venerd\u00ec dalle 09:00 alle 19:00. Surfintrip consegner\u00e0 ai propri clienti i fogli di reclamo quando li richiederanno, compiler\u00e0 l&#8217;intera casella dati che dovr\u00e0 essere compilata dall&#8217;azienda e fornir\u00e0 spiegazioni e dati necessari per il corretto completamento. Il richiedente deve conservare la copia verde per il record e inviare l&#8217;originale (copia bianca) al Ministero responsabile per il turismo. Il richiedente pu\u00f2 allegare alla copia originale tali prove o documenti che ritiene necessari. In caso di reclami sui prezzi sar\u00e0 obbligatoria la presentazione della fattura. Surfintrip s\u2019impegna ad inviare la copia di colore blu al Ministero competente in materia di turismo conservando la copia rosa entro un mese dalla data del reclamo.\u00a0<\/p><p>\u00a0<\/p><p>Se, invece, desideri presentare un reclamo online, inviaci una e-mail a info@surfintrip.com con i tuoi dati personali indicando il motivo del reclamo. Se lo richiedi, sar\u00e0 nostra cura inviarti, per posta ordinaria, un modulo di reclamo.<\/p><p>\u00a0<\/p><p>La Commissione europea mette a disposizione dei consumatori che risiedono nell&#8217;Unione europea una pagina Web (http:\/\/ec.europa.eu\/odr) in cui possono essere trattati i reclami riguardanti i loro acquisti online.\u00a0<\/p><p>\u00a0<\/p><p><strong>11. Legge applicabile, giurisdizione e risoluzione delle controversie<\/strong><\/p><p>\u00a0<\/p><p>I presenti Termini verranno interpretati in conformit\u00e0 alla legislazione dello Stato della Spagna, indipendentemente da qualunque disposizione relativa al conflitto di leggi. Lei e noi ci impegniamo a devolvere alla giurisdizione personale di un tribunale ubicato in Spagna, qualunque azione per cui le parti si riservino il diritto di chiedere un decreto di ingiunzione o altro provvedimento simile in un tribunale competente per giurisdizione. Lei e Surfintrip convenite che qualsiasi disputa, reclamo o controversia derivante da o correlata a questi Termini o alla loro violazione, risoluzione, applicazione, interpretazione e validit\u00e0 ovvero all\u2019utilizzo del Servizio o all\u2019uso del Sito il foro competente \u00e8 Las Palmas de Gran Canaria.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Termini e condizioni generali 1. Premessa I presenti Termini e Condizioni generali (d\u2019ora in poi globalmente i \u201cTermini\u201d) forniscono informazioni importanti riguardanti il funzionamento dei nostri servizi, i vostri diritti legali, mezzi di ricorso, requisiti, limitazioni e restrizioni, una clausola relativa alla giurisdizione e al foro delle controversie, e gli obblighi di rispettare le leggi [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v21.6) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Note legale - surfintriptravel<\/title>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Note legale\" \/>\n<meta property=\"og:description\" content=\"Termini e condizioni generali 1. Premessa I presenti Termini e Condizioni generali (d\u2019ora in poi globalmente i \u201cTermini\u201d) forniscono informazioni importanti riguardanti il funzionamento dei nostri servizi, i vostri diritti legali, mezzi di ricorso, requisiti, limitazioni e restrizioni, una clausola relativa alla giurisdizione e al foro delle controversie, e gli obblighi di rispettare le leggi [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/surfintriptravel.com\/it\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"surfintriptravel\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-16T12:35:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"19 minuti\" \/>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Note legale - surfintriptravel","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"it_IT","og_type":"article","og_title":"Note legale","og_description":"Termini e condizioni generali 1. Premessa I presenti Termini e Condizioni generali (d\u2019ora in poi globalmente i \u201cTermini\u201d) forniscono informazioni importanti riguardanti il funzionamento dei nostri servizi, i vostri diritti legali, mezzi di ricorso, requisiti, limitazioni e restrizioni, una clausola relativa alla giurisdizione e al foro delle controversie, e gli obblighi di rispettare le leggi [&hellip;]","og_url":"https:\/\/surfintriptravel.com\/it\/aviso-legal\/","og_site_name":"surfintriptravel","article_modified_time":"2023-08-16T12:35:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"19 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/surfintriptravel.com\/it\/aviso-legal\/","url":"https:\/\/surfintriptravel.com\/it\/aviso-legal\/","name":"Note legale - surfintriptravel","isPartOf":{"@id":"https:\/\/surfintriptravel.com\/it\/#website"},"datePublished":"2023-08-09T09:21:08+00:00","dateModified":"2023-08-16T12:35:45+00:00","breadcrumb":{"@id":"https:\/\/surfintriptravel.com\/it\/aviso-legal\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/surfintriptravel.com\/it\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/surfintriptravel.com\/it\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/surfintriptravel.com\/it\/"},{"@type":"ListItem","position":2,"name":"Note legale"}]},{"@type":"WebSite","@id":"https:\/\/surfintriptravel.com\/it\/#website","url":"https:\/\/surfintriptravel.com\/it\/","name":"surfintriptravel","description":"","publisher":{"@id":"https:\/\/surfintriptravel.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/surfintriptravel.com\/it\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/surfintriptravel.com\/it\/#organization","name":"surfintriptravel","url":"https:\/\/surfintriptravel.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/surfintriptravel.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/surfintriptravel.com\/wp-content\/uploads\/2023\/08\/Logo-header.svg","contentUrl":"https:\/\/surfintriptravel.com\/wp-content\/uploads\/2023\/08\/Logo-header.svg","width":367,"height":36,"caption":"surfintriptravel"},"image":{"@id":"https:\/\/surfintriptravel.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/pages\/12880"}],"collection":[{"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/comments?post=12880"}],"version-history":[{"count":11,"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/pages\/12880\/revisions"}],"predecessor-version":[{"id":13042,"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/pages\/12880\/revisions\/13042"}],"wp:attachment":[{"href":"https:\/\/surfintriptravel.com\/it\/wp-json\/wp\/v2\/media?parent=12880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}